{"id":571,"date":"2025-07-01T14:09:25","date_gmt":"2025-07-01T06:09:25","guid":{"rendered":"https:\/\/saimoen.com\/products\/s70-sweep-type-sampling-machines\/"},"modified":"2025-10-28T15:49:21","modified_gmt":"2025-10-28T07:49:21","slug":"s70-sweep-type-sampling-machines","status":"publish","type":"products","link":"https:\/\/www.saimoen.com\/es\/productos\/maquinas-de-muestreo-de-barrido-s70\/","title":{"rendered":"M\u00c1QUINAS DE MUESTREO DE BARRIDO S70"},"content":{"rendered":"<div class=\"p_content\">\n<img decoding=\"async\" src=\"https:\/\/saimoen.com\/wp-content\/uploads\/2025\/07\/1-12092Q425010-L.jpg\"><\/p>\n<p>La m\u00e1quina de muestreo de barrido modelo S70 de Saimo est\u00e1 especialmente dise\u00f1ada para obtener una muestra a granel representativa directamente del material en una cinta transportadora. Se compone de un cabezal de muestreo de barrido o cortador, un dispositivo de accionamiento, detector de posici\u00f3n e incluye una carcasa de acero a prueba de polvo. El cabezal de muestreo o cortador, fabricado en acero inoxidable, est\u00e1 equipado con un contrapeso que garantiza un funcionamiento preciso y fiable. Accionado por un motorreductor, el cabezal de corte rotativo realiza un ciclo completo que permite obtener una secci\u00f3n completa de material en la cinta m\u00f3vil. A continuaci\u00f3n, la muestra se introduce en la unidad de muestreo a trav\u00e9s de un conducto para su posterior trituraci\u00f3n y divisi\u00f3n.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La m\u00e1quina de muestreo de barrido modelo S70 de Saimo est\u00e1 especialmente dise\u00f1ada para obtener una muestra a granel representativa directamente del material en una cinta transportadora. Se compone de un cabezal de muestreo de barrido o cortador, un dispositivo de accionamiento, detector de posici\u00f3n e incluye una carcasa de acero a prueba de polvo. El cabezal de muestreo o cortador fabricado en acero inoxidable est\u00e1 equipado [...]<\/p>","protected":false},"featured_media":572,"template":"","adweb_product_categories":[54,64,65],"adweb_product_tags":[77],"class_list":["post-571","products","type-products","status-publish","has-post-thumbnail","hentry","adweb_product_cat-bulk-handling-division","adweb_product_cat-bulk-material-detection","adweb_product_cat-sweep-sampling-system","adweb_product_tag-bulk-handling-division-bulk-material-detection-sweep-sampling-system"],"gallery":[573],"order":null,"acf":[],"_links":{"self":[{"href":"https:\/\/www.saimoen.com\/es\/wp-json\/wp\/v2\/adweb_products\/571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saimoen.com\/es\/wp-json\/wp\/v2\/adweb_products"}],"about":[{"href":"https:\/\/www.saimoen.com\/es\/wp-json\/wp\/v2\/types\/products"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.saimoen.com\/es\/wp-json\/wp\/v2\/media\/572"}],"wp:attachment":[{"href":"https:\/\/www.saimoen.com\/es\/wp-json\/wp\/v2\/media?parent=571"}],"wp:term":[{"taxonomy":"adweb_product_cat","embeddable":true,"href":"https:\/\/www.saimoen.com\/es\/wp-json\/wp\/v2\/adweb_product_categories?post=571"},{"taxonomy":"adweb_product_tag","embeddable":true,"href":"https:\/\/www.saimoen.com\/es\/wp-json\/wp\/v2\/adweb_product_tags?post=571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}